{"id":1980,"date":"2022-03-26T23:34:56","date_gmt":"2022-03-26T23:34:56","guid":{"rendered":"https:\/\/cnj.cl\/colegio\/?p=1980"},"modified":"2024-05-28T00:15:36","modified_gmt":"2024-05-28T00:15:36","slug":"mensaje-director-inicio-ano-escolar-2022","status":"publish","type":"post","link":"https:\/\/cnj.cl\/colegio\/2022\/03\/26\/mensaje-director-inicio-ano-escolar-2022\/","title":{"rendered":"MENSAJE DIRECTOR INICIO A\u00d1O ESCOLAR 2024"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Querida Comunidad Educativa del Colegio Ni\u00f1o Jes\u00fas:<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1981\" src=\"https:\/\/cnj.cl\/colegio\/wp-content\/uploads\/2022\/03\/Director-283x300.jpg\" alt=\"\" width=\"283\" height=\"300\" srcset=\"https:\/\/cnj.cl\/colegio\/wp-content\/uploads\/2022\/03\/Director-283x300.jpg 283w, https:\/\/cnj.cl\/colegio\/wp-content\/uploads\/2022\/03\/Director.jpg 500w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" \/>Reciba cada uno de ustedes un afectuoso saludo, en este nuevo a\u00f1o escolar que estamos iniciando. De manera especial, saludamos a todas las familias que se integran\u00a0 a nuestro Proyecto Educativo. A ustedes queridas familias, que dan sus primeros pasos en esta a\u00f1osa y prestigiosa instituci\u00f3n que ya tiene 106 a\u00f1os de vida, en nombre de todos quienes formamos parte del colegio Ni\u00f1o Jes\u00fas, les damos una cari\u00f1osa bienvenida y desde ya, las y los invitamos a caminar con nosotros, para acompa\u00f1ar a sus hijos y pupilos, durante el tiempo que permanecer\u00e1n en nuestra querida instituci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El retorno a clases nos sorprende en medio de un sin n\u00famero de sucesos que han marcado la vida y la historia de nuestra naci\u00f3n y el mundo. No podemos quedar ajenos\u00a0 a los terribles incendios en nuestro pa\u00eds, en donde incluso familias ligadas fuertemente al colegio, lo han perdido todo. No podemos abstraernos tampoco, de los hechos de violencia que viven los pa\u00edses en guerra y de la intolerancia religiosa en los lugares en donde no aceptan Buena Noticia de Jes\u00fas, llegando incluso a secuestrar y asesinar a sacerdotes y religiosas que anuncian el Evangelio de Jes\u00fas. De manera especial, rezamos por las v\u00edctimas en Burkina Faso en \u00c1frica Occidental, lugar de misi\u00f3n de nuestra Congregaci\u00f3n, en donde un grupo de terroristas acab\u00f3 con la vida de por lo menos 15 personas en una iglesia cat\u00f3lica en EssaKane-Vilage.<\/p>\n<p style=\"text-align: justify;\">En medio de todo este desolador panorama mundial y nacional, como comunidad creyente que busca al Se\u00f1or por medio de la inteligencia, la educaci\u00f3n, la formaci\u00f3n val\u00f3rica y la evangelizaci\u00f3n, es que queremos ser constructores de paz, justicia y esperanza.<\/p>\n<p style=\"text-align: justify;\">Queremos trabajar tambi\u00e9n, por una educaci\u00f3n de excelencia, que permita desarrollar espacios de aprendizajes inclusivos y diversos, para que cada estudiante, desde su propio curr\u00edculo personal y familiar, se integren a la propuesta pedag\u00f3gica y formativa de nuestro colegio, para que logren desarrollar sus habilidades, por medio de \u201c<em>una gesti\u00f3n acad\u00e9mica que impacte positivamente en los aprendizajes de los estudiantes, considerando los sellos, valores y principios institucionales presentes en el PEI, en vistas\u00a0 a la consolidaci\u00f3n de un curr\u00edculum integral, seg\u00fan la propuesta val\u00f3rica y religiosa de la Congregaci\u00f3n Hermanas del Ni\u00f1o Jes\u00fas\u201d<\/em><strong>. <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><strong>Adem\u00e1s de lo antes se\u00f1alado, quisiera invitarlos a que, frente alguna dificultad en el proceso educativo de nuestros estudiantes, pudi\u00e9semos reforzar el di\u00e1logo con los estamentos y personas correspondientes, para que en conjunto busquemos lo mejor para nuestros hijos e hijas. No somos dioses y nos podemos equivocar, es por eso que el di\u00e1logo respetuoso y oportuno, son herramientas primordiales en este proceso de ense\u00f1anza y aprendizaje, del cual todos formamos parte. Y como siempre lo he dicho en diferentes oportunidades: <\/strong><em>\u201cNuestro anhelo m\u00e1s profundo como colegio, es que todos podamos contribuir a que los estudiantes aprendan y den frutos de sus aprendizajes. Para ello, es de vital importancia el compromiso de todos los docentes y asistentes de la educaci\u00f3n. Pero tambi\u00e9n es primordial el apoyo, contenci\u00f3n y la preocupaci\u00f3n que los padres demuestren durante todo el proceso escolar de sus hijos y pupilos\u201d.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0<\/em><em>Que nuestro Padre Dios por intercesi\u00f3n de nuestra fundadora Ana Mar\u00eda Martel, nos bendiga abundantemente y nos acompa\u00f1e en todos los desaf\u00edos que tendremos en este nuevo a\u00f1o escolar. <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p style=\"text-align: center;\"><em>Fraternalmente:<\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00d3scar B\u00f3rquez L\u00f3pez<\/em><\/p>\n<p style=\"text-align: center;\"><em>Director Colegio Ni\u00f1o Jes\u00fas<\/em><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Querida Comunidad Educativa del Colegio Ni\u00f1o Jes\u00fas: Reciba cada uno de ustedes un afectuoso saludo, en este nuevo a\u00f1o escolar que estamos iniciando. De manera especial, saludamos a todas las familias que se integran\u00a0 a nuestro Proyecto Educativo. A ustedes queridas familias, que dan sus primeros pasos en esta a\u00f1osa y prestigiosa instituci\u00f3n que ya tiene 106 a\u00f1os de vida, en nombre de todos quienes formamos parte del colegio Ni\u00f1o Jes\u00fas, les damos una cari\u00f1osa bienvenida y desde ya, las y los invitamos a caminar con nosotros, para acompa\u00f1ar a sus hijos y pupilos, durante el tiempo que permanecer\u00e1n en nuestra querida instituci\u00f3n. El retorno a clases nos sorprende en medio de un sin n\u00famero de sucesos que han marcado la vida y la historia de nuestra naci\u00f3n y el mundo. No podemos quedar ajenos\u00a0 a los terribles incendios en nuestro pa\u00eds, en donde incluso familias ligadas fuertemente al colegio, lo han perdido todo. No podemos abstraernos tampoco, de los hechos de violencia que viven los pa\u00edses en guerra y de la intolerancia religiosa en los lugares en donde no aceptan Buena Noticia de Jes\u00fas, llegando incluso a secuestrar y asesinar a sacerdotes y religiosas que anuncian el Evangelio de&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":1981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[41,42],"tags":[],"class_list":["post-1980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-mensaje-destacados"],"_links":{"self":[{"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/posts\/1980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/comments?post=1980"}],"version-history":[{"count":5,"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/posts\/1980\/revisions"}],"predecessor-version":[{"id":11010,"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/posts\/1980\/revisions\/11010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/media\/1981"}],"wp:attachment":[{"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/media?parent=1980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/categories?post=1980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnj.cl\/colegio\/wp-json\/wp\/v2\/tags?post=1980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}