			<link rel="stylesheet" id="basel-el-section-title-css" href="https://cnj.cl/web/wp-content/themes/basel/css/parts/el-section-title.min.css?ver=5.6.1" type="text/css" media="all" /> 			{"id":32449,"date":"2026-02-13T21:29:15","date_gmt":"2026-02-13T21:29:15","guid":{"rendered":"https:\/\/cnj.cl\/web\/?page_id=32449"},"modified":"2026-04-28T16:41:05","modified_gmt":"2026-04-28T16:41:05","slug":"pastoral","status":"publish","type":"page","link":"https:\/\/cnj.cl\/web\/estamentos\/pastoral\/","title":{"rendered":"Pastoral"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_single_image image=&#8221;32619&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border&#8221; css_animation=&#8221;fadeIn&#8221;][vc_column_text css=&#8221;&#8221;]<\/p>\n<p style=\"text-align: justify;\">El departamento de pastoral est\u00e1 conformado por miembros de la comunidad educativa, quienes buscan en su vida servir y contribuir a la formaci\u00f3n de estudiantes, docentes, asistentes de la educaci\u00f3n, padres y apoderados pertenecientes a nuestro colegio, por medio de un liderazgo pastoral que se fundamenta e inspira en la figura de Ana Mar\u00eda Martel, fundadora de la Congregaci\u00f3n Hermanas del Ni\u00f1o Jes\u00fas. Actualmente el equipo de pastoral del colegio est\u00e1 conformado por:<\/p>\n<ul>\n<li>Hna. Pilar Salzar Pascal<\/li>\n<li>\u00d3scar B\u00f3rquez L\u00f3pez<\/li>\n<li>M\u00f3nica Pacheco Guzm\u00e1n<\/li>\n<li>Tania Lozano Mu\u00f1oz<\/li>\n<li>Vivian Far\u00edas Ballestero<\/li>\n<\/ul>\n<p>[\/vc_column_text]<div class=\"title-wrapper  basel-title-color-default basel-title-style-default basel-title-size-small text-left \"><div class=\"liner-continer\"> <span class=\"left-line\"><\/span> <h4 class=\"title\" >CONOCE NUESTRO DEPARTAMENTO DE PASTORAL:<span class=\"title-separator\"><span><\/span><\/span><\/h4> <span class=\"right-line\"><\/span> <\/div><\/div><div class=\"basel-button-wrapper text-left\"><a href=\"https:\/\/cnj.cl\/colegio\/wp-content\/uploads\/2024\/05\/PASTORAL.pdf\" title=\"\" target=\"_blank\" class=\"btn btn-color-primary btn-style-bordered btn-size-default\">Departamento de Pastoral CNJ<\/a><\/div>[vc_separator color=&#8221;white&#8221;]<div class=\"title-wrapper  basel-title-color-default basel-title-style-default basel-title-size-small text-left \"><div class=\"liner-continer\"> <span class=\"left-line\"><\/span> <h4 class=\"title\" >IDEARIO PASTORAL DEL COLEGIO NI\u00d1O JES\u00daS:<span class=\"title-separator\"><span><\/span><\/span><\/h4> <span class=\"right-line\"><\/span> <\/div><\/div><div class=\"basel-button-wrapper text-left\"><a href=\"https:\/\/cnj.cl\/colegio\/wp-content\/uploads\/2024\/05\/IDEARIO_DEF.pdf\" title=\"\" target=\"_blank\" class=\"btn btn-color-primary btn-style-bordered btn-size-default\">Descargar documento completo.<\/a><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_separator color=&#8221;white&#8221;]<div class=\"title-wrapper  basel-title-color-primary basel-title-style-default basel-title-size-default text-center \"><div class=\"liner-continer\"> <span class=\"left-line\"><\/span> <h4 class=\"title\" >Noticias destacadas de Pastoral<span class=\"title-separator\"><span><\/span><\/span><\/h4> <span class=\"right-line\"><\/span> <\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;]\t\t\t<link rel=\"stylesheet\" id=\"basel-blog-general-css\" href=\"https:\/\/cnj.cl\/web\/wp-content\/themes\/basel\/css\/parts\/blog-general.min.css?ver=5.6.1\" type=\"text\/css\" media=\"all\" \/> \t\t\t<div class=\"basel-blog-holder row \" id=\"6a5733e26bbe4\" data-paged=\"1\" data-atts=\"{&quot;post_type&quot;:&quot;post&quot;,&quot;include&quot;:&quot;&quot;,&quot;custom_query&quot;:&quot;&quot;,&quot;taxonomies&quot;:&quot;49&quot;,&quot;pagination&quot;:&quot;&quot;,&quot;parts_title&quot;:&quot;1&quot;,&quot;parts_meta&quot;:&quot;1&quot;,&quot;parts_text&quot;:&quot;1&quot;,&quot;parts_media&quot;:true,&quot;parts_btn&quot;:&quot;0&quot;,&quot;items_per_page&quot;:12,&quot;offset&quot;:&quot;&quot;,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;DESC&quot;,&quot;meta_key&quot;:&quot;&quot;,&quot;exclude&quot;:&quot;&quot;,&quot;class&quot;:&quot;&quot;,&quot;ajax_page&quot;:&quot;&quot;,&quot;img_size&quot;:&quot;medium&quot;,&quot;blog_design&quot;:&quot;default-alt&quot;,&quot;blog_columns&quot;:&quot;3&quot;}\">\n<article id=\"post-31968\" class=\"blog-design-default-alt blog-post-loop blog-style- post-31968 post type-post status-publish format-standard has-post-thumbnail hentry category-archivo category-pastoral\">\n\t\t\t\t\t\t<div class=\"meta-post-categories\"><a href=\"https:\/\/cnj.cl\/web\/category\/archivo\/\" rel=\"category tag\">ARCHIVO<\/a>, <a href=\"https:\/\/cnj.cl\/web\/category\/pastoral\/\" rel=\"category tag\">PASTORAL<\/a><\/div>\n\t\t\n\t\t\t\t\t<h3 class=\"entry-title\">\n\t\t\t\t<a href=\"https:\/\/cnj.cl\/web\/comunidad-del-colegio-nino-jesus-de-lota-vive-profunda-jornada-pastoral-de-cara-al-2026\/\" rel=\"bookmark\">Comunidad del Colegio Ni\u00f1o Jes\u00fas de Lota vive profunda Jornada Pastoral de cara al 2026<\/a>\n\t\t\t<\/h3>\n\t\t\n\t\t\t\t\t<div class=\"entry-meta basel-entry-meta\">\n\t\t\t\t\t\t\t<ul class=\"entry-meta-list\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<li class=\"modified-date\"><time class=\"updated\" datetime=\"2026-03-04T00:43:47+00:00\">marzo 4, 2026<\/time><\/li>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"meta-author\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPosted by\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cnj.cl\/web\/author\/admin\/\" rel=\"author\">\n\t\t\t\t\t\t\t\t<span class=\"vcard author author_name\">\n\t\t\t\t\t\t\t\t\t<span class=\"fn\">admin<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t<header class=\"entry-header\">\n\t\t\t\t\t\t\t\t<figure id=\"carousel-234\" class=\"entry-thumbnail\" >\n\t\t\t\t\t\t\t<div class=\"post-date\" onclick=\"\">\n\t\t\t\t<span class=\"post-date-day\">\n\t\t\t\t\t23\t\t\t\t<\/span>\n\t\t\t\t<span class=\"post-date-month\">\n\t\t\t\t\tDic\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t\t\t<div class=\"post-img-wrapp\">\n\t\t\t\t\t\t<a href=\"https:\/\/cnj.cl\/web\/comunidad-del-colegio-nino-jesus-de-lota-vive-profunda-jornada-pastoral-de-cara-al-2026\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"204\" src=\"https:\/\/cnj.cl\/web\/wp-content\/uploads\/2026\/02\/IMG_20251223_111124772_HDR-300x204.jpg\" class=\"attachment-large wp-post-image attachment-medium\" alt=\"\" title=\"IMG_20251223_111124772_HDR\" srcset=\"https:\/\/cnj.cl\/web\/wp-content\/uploads\/2026\/02\/IMG_20251223_111124772_HDR-300x204.jpg 300w, https:\/\/cnj.cl\/web\/wp-content\/uploads\/2026\/02\/IMG_20251223_111124772_HDR-768x521.jpg 768w, https:\/\/cnj.cl\/web\/wp-content\/uploads\/2026\/02\/IMG_20251223_111124772_HDR.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"post-image-mask\">\n\t\t\t\t\t\t<a href=\"https:\/\/cnj.cl\/web\/comunidad-del-colegio-nino-jesus-de-lota-vive-profunda-jornada-pastoral-de-cara-al-2026\/\">Leer m\u00e1s<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/figure>\n\t\t\n\t\t\n\t<\/header><!-- .entry-header -->\n\n\t\t\t<div class=\"entry-content\">\n\t\t\t\r\nEl pasado jueves 23 de diciembre, el personal del\u00a0Colegio Ni\u00f1o Jes\u00fas de Lota\u00a0se traslad\u00f3 hasta el sector de Patagual para participar en su Jornada Pastoral, centrada en la reflexi\u00f3n de los valores del Proyecto...\t\t\t\t\t<\/div><!-- .entry-content -->\n\t\n\t<div class=\"liner-continer\">\n\t\t<span class=\"left-line\"><\/span>\n\t\t\t\t\t<link rel=\"stylesheet\" id=\"basel-el-social-icons-css\" href=\"https:\/\/cnj.cl\/web\/wp-content\/themes\/basel\/css\/parts\/el-social-icons.min.css?ver=5.6.1\" type=\"text\/css\" media=\"all\" \/> \t\t\t\n\t\t\t<ul class=\"social-icons text-center icons-design-circle icons-size-small social-share \">\n\t\t\t\t\t\t\t\t\t<li class=\"social-facebook\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/cnj.cl\/web\/comunidad-del-colegio-nino-jesus-de-lota-vive-profunda-jornada-pastoral-de-cara-al-2026\/\" target=\"_blank\" class=\"\"><i class=\"fa fa-facebook\"><\/i><span class=\"basel-social-icon-name\">Facebook<\/span><\/a><\/li>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<li class=\"social-twitter\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/twitter.com\/share?url=https:\/\/cnj.cl\/web\/comunidad-del-colegio-nino-jesus-de-lota-vive-profunda-jornada-pastoral-de-cara-al-2026\/\" target=\"_blank\" class=\"\"><i class=\"fa fa-twitter\"><\/i><span class=\"basel-social-icon-name\">Twitter<\/span><\/a><\/li>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<li class=\"social-pinterest\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/cnj.cl\/web\/comunidad-del-colegio-nino-jesus-de-lota-vive-profunda-jornada-pastoral-de-cara-al-2026\/&media=https:\/\/cnj.cl\/web\/wp-content\/uploads\/2026\/02\/IMG_20251223_111124772_HDR.jpg\" target=\"_blank\" class=\"\"><i class=\"fa fa-pinterest\"><\/i><span class=\"basel-social-icon-name\">Pinterest<\/span><\/a><\/li>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<li class=\"social-linkedin\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/cnj.cl\/web\/comunidad-del-colegio-nino-jesus-de-lota-vive-profunda-jornada-pastoral-de-cara-al-2026\/\" target=\"_blank\" class=\"\"><i class=\"fa fa-linkedin\"><\/i><span class=\"basel-social-icon-name\">LinkedIn<\/span><\/a><\/li>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<li class=\"social-tg\"><a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/telegram.me\/share\/url?url=https:\/\/cnj.cl\/web\/comunidad-del-colegio-nino-jesus-de-lota-vive-profunda-jornada-pastoral-de-cara-al-2026\/\" target=\"_blank\" class=\"\"><i class=\"fa fa-telegram\"><\/i><span class=\"basel-social-icon-name\">Telegram<\/span><\/a><\/li>\n\t\t\t\t\n\t\t\t<\/ul>\n\n\t\t\t\t<span class=\"right-line\"><\/span>\n\t<\/div>\n\n\t<\/article><!-- #post -->\n\n<\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;33366&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_single_image image=&#8221;32619&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border&#8221; css_animation=&#8221;fadeIn&#8221;][vc_column_text css=&#8221;&#8221;] El departamento de pastoral est\u00e1 conformado por miembros de la comunidad educativa, quienes<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":32010,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-32449","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cnj.cl\/web\/wp-json\/wp\/v2\/pages\/32449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnj.cl\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cnj.cl\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cnj.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cnj.cl\/web\/wp-json\/wp\/v2\/comments?post=32449"}],"version-history":[{"count":20,"href":"https:\/\/cnj.cl\/web\/wp-json\/wp\/v2\/pages\/32449\/revisions"}],"predecessor-version":[{"id":34295,"href":"https:\/\/cnj.cl\/web\/wp-json\/wp\/v2\/pages\/32449\/revisions\/34295"}],"up":[{"embeddable":true,"href":"https:\/\/cnj.cl\/web\/wp-json\/wp\/v2\/pages\/32010"}],"wp:attachment":[{"href":"https:\/\/cnj.cl\/web\/wp-json\/wp\/v2\/media?parent=32449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}